{"id":10094,"date":"2025-04-16T02:10:00","date_gmt":"2025-04-16T02:10:00","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-de-posicion-del-arbol-de-levas-cmp-ys6a12k073ab-de-alta-calidad-y-nuevo-para-ford\/"},"modified":"2025-07-07T04:03:59","modified_gmt":"2025-07-07T04:03:59","slug":"sensor-de-posicion-del-arbol-de-levas-cmp-ys6a12k073ab-de-alta-calidad-y-nuevo-para-ford","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-de-posicion-del-arbol-de-levas-cmp-ys6a12k073ab-de-alta-calidad-y-nuevo-para-ford\/","title":{"rendered":"Sensor de posici\u00f3n del \u00e1rbol de levas CMP YS6A12K073AB de alta calidad y nuevo para Ford"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de fabricante original<\/th>\n<th align=\"left\">YS6A12K073AB<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">T\u00edtulo<\/td>\n<td align=\"left\">Sensor de posici\u00f3n del \u00e1rbol de levas<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Fiesta Zetec 1.25L 96-00, Fiesta Supercharger 1.0L 04-08, Fiesta Power 1.6L 02-04, Ford KA 1.3L 96-02<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>El YS6A12K073AB es un sensor de posici\u00f3n del \u00e1rbol de levas CMP de alta gama, completamente nuevo, dise\u00f1ado para veh\u00edculos Ford. Dise\u00f1ado con precisi\u00f3n, monitorea con precisi\u00f3n la posici\u00f3n del \u00e1rbol de levas. Al proporcionar datos en tiempo real, permite que los motores Ford optimicen el encendido y la inyecci\u00f3n de combustible, mejorando el rendimiento y el ahorro de combustible. Fabricado con materiales de alta calidad, este sensor garantiza una larga duraci\u00f3n, lo que lo convierte en la opci\u00f3n ideal para reemplazar una unidad desgastada y mantener su Ford funcionando sin problemas.   <\/p>\n","protected":false},"featured_media":2391,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[301],"product_tag":[],"class_list":["post-10094","product","type-product","status-publish","has-post-thumbnail","product_cat-sensor-de-posicion-del-arbol-de-levas-cmp","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/10094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=10094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/2391"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=10094"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=10094"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=10094"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=10094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}