{"id":10133,"date":"2025-04-14T07:01:18","date_gmt":"2025-04-14T07:01:18","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-de-temperatura-del-agua-del-refrigerante-del-motor-19236568-para-cadillac\/"},"modified":"2025-07-07T06:26:40","modified_gmt":"2025-07-07T06:26:40","slug":"sensor-de-temperatura-del-agua-del-refrigerante-del-motor-19236568-para-cadillac","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-de-temperatura-del-agua-del-refrigerante-del-motor-19236568-para-cadillac\/","title":{"rendered":"Sensor de temperatura del agua del refrigerante del motor 19236568 para Cadillac"},"content":{"rendered":"<p>Sensor de temperatura del agua de GM Cadillac<\/p>\n<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td align=\"left\">OEM No.<\/td>\n<td align=\"left\">213-4514 213-4333 19236568 15326388 15369305 12191170 12608814<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Para Chevy Cavalier, Cobalt, Equinox, Express, Silverado 1500 y 2500 HD<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Calidad<\/td>\n<td align=\"left\">Inspecci\u00f3n de calidad del 100% con un a\u00f1o de garant\u00eda<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n<p>N\u00fameros de intercambio de este sensor de temperatura del agua:<br \/>\n213-4514 213-4333 19236568 15326388 15369305 12191170 12608814<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sensor de temperatura del refrigerante del motor para Buick, Chevrolet y Pontiac: 15326388, 19236568, 15369305, 12191170, 12608814, 96182634, 96181508<\/p>\n","protected":false},"featured_media":2167,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[299,317],"product_tag":[],"class_list":["post-10133","product","type-product","status-publish","has-post-thumbnail","product_cat-sensores-automotrices","product_cat-sensor-de-temperatura-es","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/10133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=10133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/2167"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=10133"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=10133"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=10133"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=10133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}