{"id":10149,"date":"2025-04-14T03:44:22","date_gmt":"2025-04-14T03:44:22","guid":{"rendered":"https:\/\/ws-diesel.com\/valvula-de-control-de-succion-55493549-valvula-scv-para-gm-chevrolet\/"},"modified":"2025-07-07T06:40:22","modified_gmt":"2025-07-07T06:40:22","slug":"valvula-de-control-de-succion-55493549-valvula-scv-para-gm-chevrolet","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/valvula-de-control-de-succion-55493549-valvula-scv-para-gm-chevrolet\/","title":{"rendered":"V\u00e1lvula de control de succi\u00f3n 55493549 V\u00e1lvula SCV para GM Chevrolet"},"content":{"rendered":"<p>V\u00e1lvula de control de succi\u00f3n de la bomba de combustible GM<\/p>\n<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td align=\"left\">N.\u00b0 de fabricante original (OEM)<\/td>\n<td align=\"left\">55493549 294000-1685<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Solicitud<\/td>\n<td align=\"left\">Para repuestos de Buick, GMC, Cadillac, Hummer, Saturn, Oldsmobile, Pontiac y Chevrolet<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">Un a\u00f1o<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n<div>\n<p><strong>N\u00famero de pieza:<\/strong><br \/>\n55493549 294000-1685<br \/>\nEsta v\u00e1lvula SCV es compatible con:<br \/>\nChevrolet Colorado 2016-2020<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>55493549 V\u00e1lvula de control de succi\u00f3n de combustible di\u00e9sel, v\u00e1lvula reguladora de presi\u00f3n solenoide SCV 55593780 para bomba de riel com\u00fan Chevrolet GMC<\/p>\n","protected":false},"featured_media":2139,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[289,297],"product_tag":[],"class_list":["post-10149","product","type-product","status-publish","has-post-thumbnail","product_cat-valvulas-de-control-automotriz","product_cat-valvula-scv-es","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/10149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=10149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/2139"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=10149"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=10149"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=10149"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=10149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}