{"id":10181,"date":"2025-04-10T10:33:23","date_gmt":"2025-04-10T10:33:23","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-de-nivel-de-refrigerante-1850746-para-camion-daf\/"},"modified":"2025-07-07T07:13:24","modified_gmt":"2025-07-07T07:13:24","slug":"sensor-de-nivel-de-refrigerante-1850746-para-camion-daf","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-de-nivel-de-refrigerante-1850746-para-camion-daf\/","title":{"rendered":"Sensor de nivel de refrigerante 1850746 para cami\u00f3n DAF"},"content":{"rendered":"<p>Sensor de nivel de refrigerante DAF<\/p>\n<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<tbody>\n<tr>\n<td align=\"left\">OEM No.<\/td>\n<td align=\"left\">1740757 1689941 1850746<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Camiones DAF LF-CF-XF \/ E4-E5<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Calidad<\/td>\n<td align=\"left\">Inspecci\u00f3n de calidad del 100%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n<p>N\u00fameros de intercambio:<\/p>\n<h1 title=\"MAXTRUCK - Repuestos de alta calidad para Volvo B13 (20928544, 20526768, 21390375, 23740265, 2.40573)\" data-spm-anchor-id=\"a2700.details.0.i58.6e2958e1xMAe93\">1740757 1689941 1850746<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Sensor de nivel de camiones Daf<\/p>\n","protected":false},"featured_media":1975,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[299,302],"product_tag":[],"class_list":["post-10181","product","type-product","status-publish","has-post-thumbnail","product_cat-sensores-automotrices","product_cat-sensor-de-nivel-de-refrigerante","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/10181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=10181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/1975"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=10181"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=10181"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=10181"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=10181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}