{"id":12126,"date":"2025-08-08T07:13:39","date_gmt":"2025-08-08T07:13:39","guid":{"rendered":"https:\/\/ws-diesel.com\/electrovalvula-de-alta-calidad-14956-ad20a-para-nissan-instalacion-sencilla\/"},"modified":"2025-08-10T17:34:03","modified_gmt":"2025-08-10T17:34:03","slug":"electrovalvula-de-alta-calidad-14956-ad20a-para-nissan-instalacion-sencilla","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/electrovalvula-de-alta-calidad-14956-ad20a-para-nissan-instalacion-sencilla\/","title":{"rendered":"Electrov\u00e1lvula de alta calidad 14956-AD20A para Nissan. Instalaci\u00f3n sencilla."},"content":{"rendered":"<h2><\/h2>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N\u00famero de OEM<\/th>\n<th align=\"left\">14956-AD20A<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">T\u00edtulo<\/td>\n<td align=\"left\">V\u00e1lvula solenoide<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Instalaci\u00f3n sencilla de Nissan<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2><\/h2>\n","protected":false},"excerpt":{"rendered":"<p id=\"title\" class=\"a-size-large a-spacing-none\"><span id=\"productTitle\" class=\"a-size-large product-title-word-break\">V\u00e1lvula solenoide para Nissan, accesorio para coche, 14956-AD20A, 14956-AD200, 139700-0441, 1397000441, 25819-27040, instalaci\u00f3n sencilla.<\/span><\/p>\n","protected":false},"featured_media":12117,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[94,289],"product_tag":[],"class_list":["post-12126","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categoria","product_cat-valvulas-de-control-automotriz","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/12126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=12126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/12117"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=12126"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=12126"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=12126"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=12126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}