{"id":13977,"date":"2025-10-18T04:10:43","date_gmt":"2025-10-18T04:10:43","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-de-temperatura-mopar-68088241aa-68119586aa-para-automoviles-chrysler-y-dodge\/"},"modified":"2025-10-18T04:10:43","modified_gmt":"2025-10-18T04:10:43","slug":"sensor-de-temperatura-mopar-68088241aa-68119586aa-para-automoviles-chrysler-y-dodge","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-de-temperatura-mopar-68088241aa-68119586aa-para-automoviles-chrysler-y-dodge\/","title":{"rendered":"Sensor de temperatura Mopar 68088241AA 68119586AA para autom\u00f3viles Chrysler y Dodge"},"content":{"rendered":"<h2>Sensor de temperatura del coche<\/h2>\n<p>El sensor de temperatura es compatible con:<\/p>\n<p>Chrysler 200 2015-2016;<\/p>\n<p>Dodge Dart 2013-2016;<\/p>\n<p>Fiat 500 2012-2019<\/p>\n<p>Fiat 500l 2014-2015<\/p>\n<p>Fiat 500x 2016-2018<\/p>\n<p>Jeep Cherokee 2014-2019<\/p>\n<p>Jeep Compass 2017-2019<\/p>\n<p>Jeep Renegade 2015-2020<\/p>\n<p>N\u00fameros intercambiables:<\/p>\n<p>K68119586AA 1712574 5S13290 K68088241AA 68088241AA 68119586AA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sensor de temperatura del coche El sensor de temperatura es  [&#8230;]<\/p>\n","protected":false},"featured_media":13853,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[299,317],"product_tag":[],"class_list":["post-13977","product","type-product","status-publish","has-post-thumbnail","product_cat-sensores-automotrices","product_cat-sensor-de-temperatura-es","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/13977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=13977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/13853"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=13977"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=13977"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=13977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=13977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}