{"id":15066,"date":"2025-11-18T01:53:43","date_gmt":"2025-11-18T01:53:43","guid":{"rendered":"https:\/\/ws-diesel.com\/valvula-de-control-de-presion-de-aceite-psa-9675081780-para-citroen-y-peugeot\/"},"modified":"2025-11-18T01:53:43","modified_gmt":"2025-11-18T01:53:43","slug":"valvula-de-control-de-presion-de-aceite-psa-9675081780-para-citroen-y-peugeot","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/valvula-de-control-de-presion-de-aceite-psa-9675081780-para-citroen-y-peugeot\/","title":{"rendered":"V\u00e1lvula de control de presi\u00f3n de aceite PSA 9675081780 para Citro\u00ebn y Peugeot"},"content":{"rendered":"<h2>v\u00e1lvula de control PSA<\/h2>\n<p>La v\u00e1lvula de control es compatible con v\u00e1lvulas Citro\u00ebn, Ford, Peugeot y Vauxhall.<\/p>\n<p>N\u00famero OE: 9675081780<\/p>\n","protected":false},"excerpt":{"rendered":"<p>v\u00e1lvula de control PSA La v\u00e1lvula de control es compatible  [&#8230;]<\/p>\n","protected":false},"featured_media":14986,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[289,298],"product_tag":[],"class_list":["post-15066","product","type-product","status-publish","has-post-thumbnail","product_cat-valvulas-de-control-automotriz","product_cat-valvula-vvt-es","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/15066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=15066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/14986"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=15066"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=15066"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=15066"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=15066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}