{"id":15533,"date":"2025-12-09T07:22:10","date_gmt":"2025-12-09T07:22:10","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-de-temperatura-cummins-5461596\/"},"modified":"2025-12-13T05:55:50","modified_gmt":"2025-12-13T05:55:50","slug":"sensor-de-temperatura-cummins-5461596","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-de-temperatura-cummins-5461596\/","title":{"rendered":"Sensor de temperatura Cummins 5461596"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de fabricante original<\/th>\n<th align=\"left\">5461596 \/ 5461596CUM<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">T\u00edtulo<\/td>\n<td align=\"left\">Sensor de temperatura<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Solicitud<\/td>\n<td align=\"left\">1 a\u00f1o<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n<div class=\"host-lopnbnfpjmgpbppclhclehhgafnifija\" style=\"position: relative; z-index: 2147483647;\"><\/div>\n<div class=\"host-lopnbnfpjmgpbppclhclehhgafnifija\" style=\"position: relative; z-index: 2147483647;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"ds-markdown-paragraph\">Garantice un control preciso de la temperatura en los motores Cummins con este sensor de reemplazo OEM de ajuste directo, dise\u00f1ado para un rendimiento confiable y durabilidad.<\/p>\n<p class=\"ds-markdown-paragraph\">\u2714 Coincidencia exacta: Dise\u00f1ado espec\u00edficamente para Cummins OE# 5461596 \/ 5461596CUM<br \/>\n\u2714 Detecci\u00f3n precisa: Proporciona lecturas de temperatura confiables para una gesti\u00f3n \u00f3ptima del motor<br \/>\n\u2714 Construcci\u00f3n robusta: Dise\u00f1ado para soportar entornos exigentes de veh\u00edculos comerciales<br \/>\n\u2714 Instalaci\u00f3n sencilla: Reemplazo directo para un mantenimiento eficiente<\/p>\n<div class=\"host-lopnbnfpjmgpbppclhclehhgafnifija\" style=\"position: relative; z-index: 2147483647;\"><\/div>\n<div class=\"host-lopnbnfpjmgpbppclhclehhgafnifija\" style=\"position: relative; z-index: 2147483647;\"><\/div>\n","protected":false},"featured_media":15553,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[317,299],"product_tag":[],"class_list":["post-15533","product","type-product","status-publish","has-post-thumbnail","product_cat-sensor-de-temperatura-es","product_cat-sensores-automotrices","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/15533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=15533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/15553"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=15533"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=15533"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=15533"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=15533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}