{"id":9629,"date":"2025-05-09T05:35:32","date_gmt":"2025-05-09T05:35:32","guid":{"rendered":"https:\/\/ws-diesel.com\/toyota-reliable-2227062050-valvula-de-control-de-ralenti\/"},"modified":"2025-07-05T02:17:03","modified_gmt":"2025-07-05T02:17:03","slug":"toyota-reliable-2227062050-valvula-de-control-de-ralenti","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/toyota-reliable-2227062050-valvula-de-control-de-ralenti\/","title":{"rendered":"TOYOTA Reliable 2227062050 V\u00e1lvula de control de ralent\u00ed"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de fabricante original<\/th>\n<th align=\"left\">2227062050<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Caracter\u00edstica<\/td>\n<td align=\"left\">3 TERMINALES<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Solicitud<\/td>\n<td align=\"left\">Prado 3.4L 98-04<br \/>\n4 corredores 3.4L 99-06<br \/>\nTacoma 3.4L 98-06<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00e1lvula de control de ralent\u00ed 2227062050 de alta calidad para Toyota. Regula con precisi\u00f3n el ralent\u00ed del motor, garantizando un funcionamiento suave. Dise\u00f1ada espec\u00edficamente para veh\u00edculos Toyota, mejora eficazmente el ahorro de combustible y la estabilidad de conducci\u00f3n.  <\/p>\n","protected":false},"featured_media":5415,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[294],"product_tag":[],"class_list":["post-9629","product","type-product","status-publish","has-post-thumbnail","product_cat-valvula-iac-es","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/9629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=9629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/5415"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=9629"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=9629"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=9629"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=9629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}