{"id":9647,"date":"2025-05-08T06:46:15","date_gmt":"2025-05-08T06:46:15","guid":{"rendered":"https:\/\/ws-diesel.com\/valvula-de-control-de-ralenti-chevrolet-17111826-de-alta-calidad\/"},"modified":"2025-07-05T02:38:35","modified_gmt":"2025-07-05T02:38:35","slug":"valvula-de-control-de-ralenti-chevrolet-17111826-de-alta-calidad","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/valvula-de-control-de-ralenti-chevrolet-17111826-de-alta-calidad\/","title":{"rendered":"V\u00e1lvula de control de ralent\u00ed CHEVROLET 17111826 de alta calidad"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de OEM<\/th>\n<th align=\"left\">17111826<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Caracter\u00edstica<\/td>\n<td align=\"left\">4 TERMINALES<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Optra L4 1.6L 06-12<br \/>\nCorsa L4 1.4L 96-02<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00e1lvula de control de ralent\u00ed de alta calidad 17111826 para CHEVROLET. Regula con precisi\u00f3n el ralent\u00ed del motor, garantizando un funcionamiento suave. Dise\u00f1ada espec\u00edficamente para veh\u00edculos CHEVROLET, mejora eficazmente el ahorro de combustible y la estabilidad de conducci\u00f3n.  <\/p>\n","protected":false},"featured_media":5273,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[294],"product_tag":[],"class_list":["post-9647","product","type-product","status-publish","has-post-thumbnail","product_cat-valvula-iac-es","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/9647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=9647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/5273"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=9647"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=9647"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=9647"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=9647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}