{"id":9698,"date":"2025-04-27T03:52:29","date_gmt":"2025-04-27T03:52:29","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-maf-confiable-para-hyundai-2810039000-2810039450-281134d000\/"},"modified":"2025-07-05T03:27:17","modified_gmt":"2025-07-05T03:27:17","slug":"sensor-maf-confiable-para-hyundai-2810039000-2810039450-281134d000","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-maf-confiable-para-hyundai-2810039000-2810039450-281134d000\/","title":{"rendered":"Sensor MAF confiable para Hyundai 2810039000 2810039450 281134D000"},"content":{"rendered":"\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de fabricante original (OEM)<\/th>\n<th align=\"left\">2810039000 \/ 2810039450 \/ 281134D000<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">T\u00edtulo<\/td>\n<td align=\"left\">Sensor MAF<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">12 meses<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Solicitud<\/td>\n<td align=\"left\">Carens Rondo 2.7L 08-12<br \/>\nCarnival 2.7L 06-08<br \/>\nBorrego 3.8L 06-10<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<h6 class=\"ds-markdown-paragraph\">Garantice una <strong>medici\u00f3n precisa de la entrada de aire y un rendimiento<\/strong> \u00f3ptimo del motor con este sensor MAF de <strong>grado OEM,<\/strong> dise\u00f1ado como un reemplazo directo para HYUNDAI.<\/h6>\n<p class=\"ds-markdown-paragraph\">\u2714 <strong>Triple compatibilidad con equipos originales<\/strong>: reemplaza 2810039000 \/ 2810039450 \/ 281134D000<br \/>\n\u2714 <strong>Lectura precisa del flujo de aire<\/strong>: precisi\u00f3n de se\u00f1al de \u00b11,5 %<br \/>\n\u2714 <strong>Dise\u00f1o duradero<\/strong>: carcasa resistente al calor y revestimiento anticontaminaci\u00f3n<br \/>\n\u2714 <strong>F\u00e1cil instalaci\u00f3n<\/strong>: instalaci\u00f3n inmediata<\/p>\n","protected":false},"featured_media":4011,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[310],"product_tag":[],"class_list":["post-9698","product","type-product","status-publish","has-post-thumbnail","product_cat-sensor-de-flujo-de-masa-de-aire","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/9698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=9698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/4011"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=9698"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=9698"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=9698"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=9698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}