{"id":9927,"date":"2025-04-21T02:56:41","date_gmt":"2025-04-21T02:56:41","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-de-velocidad-confiable-para-chevrolet-96473224\/"},"modified":"2025-07-05T09:22:35","modified_gmt":"2025-07-05T09:22:35","slug":"sensor-de-velocidad-confiable-para-chevrolet-96473224","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-de-velocidad-confiable-para-chevrolet-96473224\/","title":{"rendered":"Sensor de velocidad confiable para Chevrolet 96473224"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de OEM<\/th>\n<th align=\"left\">96473224<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Caracter\u00edstica<\/td>\n<td align=\"left\">TRASERO IZQUIERDO 2 TERMINALES<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Aveo L4 1.4L 1.5L 1.6L 06-14<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Asegure un rendimiento fluido de la transmisi\u00f3n con este sensor de velocidad de <strong>calidad OEM<\/strong>, dise\u00f1ado para veh\u00edculos CHEVROLET. Esta pieza de repuesto directa, <strong>100 % nueva<\/strong>, proporciona datos precisos de la velocidad de las ruedas a sus sistemas ABS y de control de tracci\u00f3n. <\/p>\n<p><strong>Caracter\u00edsticas principales:<\/strong><br \/>\n\u2714 Ajuste perfecto para CHEVROLET OE#96473224<br \/>\n\u2714 Transmisi\u00f3n precisa de la se\u00f1al de velocidad<br \/>\n\u2714 Construcci\u00f3n sellada y duradera<br \/>\n\u2714 Resistente a la humedad y la vibraci\u00f3n<\/p>\n","protected":false},"featured_media":3087,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[320,299],"product_tag":[],"class_list":["post-9927","product","type-product","status-publish","has-post-thumbnail","product_cat-sensor-de-velocidad-de-la-rueda-abs","product_cat-sensores-automotrices","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/9927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=9927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/3087"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=9927"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=9927"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=9927"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=9927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}