{"id":9954,"date":"2025-04-18T06:25:16","date_gmt":"2025-04-18T06:25:16","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-transductor-de-presion-de-aceite-diesel-detroit-0071530828-0111539228-0041534928\/"},"modified":"2025-07-05T09:39:18","modified_gmt":"2025-07-05T09:39:18","slug":"sensor-transductor-de-presion-de-aceite-diesel-detroit-0071530828-0111539228-0041534928","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-transductor-de-presion-de-aceite-diesel-detroit-0071530828-0111539228-0041534928\/","title":{"rendered":"Sensor transductor de presi\u00f3n de aceite di\u00e9sel Detroit 0071530828 0111539228 0041534928"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N\u00famero de intercambio<\/th>\n<th align=\"left\">0071530828 0111539228 0041534928<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Sensor<\/td>\n<td align=\"left\">de presi\u00f3n de aceite di\u00e9sel Detroit<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Solicitud<\/td>\n<td align=\"left\">Detroit Diesel DD15 DD13 50 MERCEDES-BENZ ATEGO Axor Actros Adblue 600 609<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Interruptor del sensor de presi\u00f3n de aceite Detroit Diesel DD15 DD13 50 compatible con BENZ ATEGO Axor Actros Adblue<\/p>\n","protected":false},"featured_media":2959,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[299,314],"product_tag":[],"class_list":["post-9954","product","type-product","status-publish","has-post-thumbnail","product_cat-sensores-automotrices","product_cat-sensor-de-presion-de-aceite","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/9954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=9954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/2959"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=9954"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=9954"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=9954"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=9954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}