{"id":9959,"date":"2025-04-18T05:55:10","date_gmt":"2025-04-18T05:55:10","guid":{"rendered":"https:\/\/ws-diesel.com\/sensor-automatico-oe-3517026910-sensor-de-posicion-del-acelerador-para-hyundai-accent-05-11-kia-rio-1-6l\/"},"modified":"2025-07-05T09:41:55","modified_gmt":"2025-07-05T09:41:55","slug":"sensor-automatico-oe-3517026910-sensor-de-posicion-del-acelerador-para-hyundai-accent-05-11-kia-rio-1-6l","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/es\/sensor-automatico-oe-3517026910-sensor-de-posicion-del-acelerador-para-hyundai-accent-05-11-kia-rio-1-6l\/","title":{"rendered":"Sensor autom\u00e1tico OE 3517026910 Sensor de posici\u00f3n del acelerador para HYUNDAI Accent 05-11 KIA Rio 1.6L"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N.\u00ba de fabricante original (OEM)<\/th>\n<th align=\"left\">3517026910 SMP: TH431 Wells: TPS4221 Tomco: 14964 Airtex: 5S9673<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Caracter\u00edstica<\/td>\n<td align=\"left\">GIRO A LA IZQUIERDA 3 TERMINALES<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garant\u00eda<\/td>\n<td align=\"left\">1 a\u00f1o<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplicaci\u00f3n<\/td>\n<td align=\"left\">Getz 1.6L 06-12 Accent 1.6L 06-10 Elantra L4 1.8L 09-13 Elantra L4 2.0L 10-14<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Sensor de posici\u00f3n del acelerador 100% probado en cuanto a calidad<\/p>\n","protected":false},"featured_media":2939,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[318],"product_tag":[],"class_list":["post-9959","product","type-product","status-publish","has-post-thumbnail","product_cat-sensor-de-posicion-del-acelerador-tps","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product\/9959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/comments?post=9959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media\/2939"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/media?parent=9959"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_brand?post=9959"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_cat?post=9959"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/es\/wp-json\/wp\/v2\/product_tag?post=9959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}