{"id":10777,"date":"2025-04-17T03:35:37","date_gmt":"2025-04-17T03:35:37","guid":{"rendered":"https:\/\/ws-diesel.com\/0k30e18131b-sensor-de-posicao-do-eixo-de-comando-cmp-novo-e-confiavel-para-kia\/"},"modified":"2025-07-08T15:51:24","modified_gmt":"2025-07-08T15:51:24","slug":"0k30e18131b-sensor-de-posicao-do-eixo-de-comando-cmp-novo-e-confiavel-para-kia","status":"publish","type":"product","link":"https:\/\/ws-diesel.com\/pt-br\/0k30e18131b-sensor-de-posicao-do-eixo-de-comando-cmp-novo-e-confiavel-para-kia\/","title":{"rendered":"0K30E18131B Sensor de posi\u00e7\u00e3o do eixo de comando CMP novo e confi\u00e1vel para KIA"},"content":{"rendered":"<\/p>\n<div class=\"table-1\">\n<p>&nbsp;<\/p>\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">N\u00ba do OEM<\/th>\n<th align=\"left\">0K30E18131B<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Caracter\u00edstica<\/td>\n<td align=\"left\">3 TERMINAIS<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Garantia<\/td>\n<td align=\"left\">1 ano<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Aplica\u00e7\u00e3o<\/td>\n<td align=\"left\">RIO L4 1.5L 02-06, RIO L4 1.6L 02-06<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Adquira este Sensor de Posi\u00e7\u00e3o do Eixo de Comando de V\u00e1lvulas CMP, novinho em folha e de alta qualidade, projetado para KIA (0K30E18131B). Ele rastreia com precis\u00e3o a posi\u00e7\u00e3o do eixo de comando, otimizando o funcionamento do motor. Projetado com materiais de alta qualidade, garante um desempenho confi\u00e1vel e duradouro, tornando-o um substituto ideal para o sensor do seu ve\u00edculo.  <\/p>\n","protected":false},"featured_media":2685,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[225,223],"product_tag":[],"class_list":["post-10777","product","type-product","status-publish","has-post-thumbnail","product_cat-sensor-de-posicao-do-eixo-de-comando-cmp","product_cat-sensores-automotivos","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/product\/10777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/comments?post=10777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/media\/2685"}],"wp:attachment":[{"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/media?parent=10777"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/product_brand?post=10777"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/product_cat?post=10777"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ws-diesel.com\/pt-br\/wp-json\/wp\/v2\/product_tag?post=10777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}